{"id":4025,"count":2,"description":"","link":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/","name":"Erlebnis Erde","slug":"erlebnis-erde","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erlebnis Erde Archive - live&amp;learn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erlebnis Erde Archive - live&amp;learn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/\" \/>\n<meta property=\"og:site_name\" content=\"live&amp;learn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/tag\\\/erlebnis-erde\\\/\",\"url\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/tag\\\/erlebnis-erde\\\/\",\"name\":\"Erlebnis Erde Archive - live&amp;learn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/tag\\\/erlebnis-erde\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/tag\\\/erlebnis-erde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erlebnis Erde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/\",\"name\":\"live&amp;learn\",\"description\":\"weil du leben lernst\",\"publisher\":{\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/#organization\",\"name\":\"live&learn\",\"url\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/liveandlearn.de\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/liveandlearn_logo.jpg\",\"contentUrl\":\"https:\\\/\\\/liveandlearn.de\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/liveandlearn_logo.jpg\",\"width\":1754,\"height\":851,\"caption\":\"live&learn\"},\"image\":{\"@id\":\"https:\\\/\\\/liveandlearn.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/liveandlearnsa\",\"https:\\\/\\\/www.instagram.com\\\/liveandlearnsa\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/19177890\\\/admin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erlebnis Erde Archive - live&amp;learn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/","og_locale":"en_US","og_type":"article","og_title":"Erlebnis Erde Archive - live&amp;learn","og_url":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/","og_site_name":"live&amp;learn","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/","url":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/","name":"Erlebnis Erde Archive - live&amp;learn","isPartOf":{"@id":"https:\/\/liveandlearn.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/liveandlearn.de\/en\/tag\/erlebnis-erde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/liveandlearn.de\/en\/"},{"@type":"ListItem","position":2,"name":"Erlebnis Erde"}]},{"@type":"WebSite","@id":"https:\/\/liveandlearn.de\/en\/#website","url":"https:\/\/liveandlearn.de\/en\/","name":"live&amp;learn","description":"weil du leben lernst","publisher":{"@id":"https:\/\/liveandlearn.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/liveandlearn.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/liveandlearn.de\/en\/#organization","name":"live&learn","url":"https:\/\/liveandlearn.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/liveandlearn.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/liveandlearn.de\/wp-content\/uploads\/2018\/04\/liveandlearn_logo.jpg","contentUrl":"https:\/\/liveandlearn.de\/wp-content\/uploads\/2018\/04\/liveandlearn_logo.jpg","width":1754,"height":851,"caption":"live&learn"},"image":{"@id":"https:\/\/liveandlearn.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/liveandlearnsa","https:\/\/www.instagram.com\/liveandlearnsa\/","https:\/\/www.linkedin.com\/company\/19177890\/admin\/"]}]}},"_links":{"self":[{"href":"https:\/\/liveandlearn.de\/en\/wp-json\/wp\/v2\/tags\/4025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/liveandlearn.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/liveandlearn.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/liveandlearn.de\/en\/wp-json\/wp\/v2\/posts?tags=4025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}